{"id":8339,"date":"2023-06-06T17:59:34","date_gmt":"2023-06-06T15:59:34","guid":{"rendered":"https:\/\/scontissimo.com\/?p=8339"},"modified":"2023-06-06T17:59:34","modified_gmt":"2023-06-06T15:59:34","slug":"la-apple-wwdc-2023","status":"publish","type":"post","link":"https:\/\/scontissimo.com\/index.php\/2023\/06\/06\/la-apple-wwdc-2023\/","title":{"rendered":"La Apple WWDC 2023"},"content":{"rendered":"\n<p>L&#8217;annuale Worldwide Developers Conference (meglio conosciuta come la Apple WWDC 2023) di Apple \u00e8 uno degli eventi tecnologici pi\u00f9 attesi dell&#8217;anno e l&#8217;edizione 2023 non ha deluso le aspettative. Durante l&#8217;evento, Apple ha svelato una serie di nuovi prodotti e aggiornamenti interessanti, tra cui l&#8217;headset <strong>Vision Pro<\/strong>, i <strong>nuovi Mac<\/strong> e la nuova versione del sistema operativo <strong>iOS 17<\/strong>.<\/p>\n\n\n\n<p>Il punto saliente della WWDC 2023 \u00e8 stata la presentazione del <strong>Vision Pro, un device AR\/VR<\/strong> molto atteso e su cui ci sono state molte indiscrezioni. Vision Pro rappresenta un importante passo avanti nel mondo della realt\u00e0 virtuale e aumentata e potrebbe avere un impatto significativo su numerosi settori. Una delle caratteristiche pi\u00f9 interessanti di Vision Pro \u00e8 l<strong>a nuova tecnologia di tracciamento<\/strong> degli occhi e dei gesti. Questa permette agli utenti di interagire con il device in modo pi\u00f9 intuitivo e naturale, rendendo pi\u00f9 facile la navigazione in ambienti di realt\u00e0 virtuale e aumentata. Il Vision Pro include inoltre una serie di <strong>videocamere che permettono agli utenti di vedere il mondo reale<\/strong> che li circonda mentre utilizzano il dispositivo. La caratteristica principale del visore infatti \u00e8 la possibilit\u00e0 di\u00a0<strong>regolare il livello di immersivit\u00e0<\/strong>\u00a0dell&#8217;ambiente virtuale. Il Vision Pro \u00e8 alimentato dall&#8217;ultimo processore di Apple, il <strong>Silicon M2<\/strong>, molto pi\u00f9 potente del suo predecessore. Questo dovrebbe consentire di eseguire con facilit\u00e0 applicazioni AR\/VR pi\u00f9 complesse e impegnative. In termini di design, il Vision Pro ha un&#8217;estetica decisamente Apple, con un look elegante e minimalista che sicuramente piacer\u00e0 ai fan degli altri prodotti dell&#8217;azienda. L&#8217;headset ovviamente \u00e8 stato progettato per essere compatibile con tutti i dispositivi Apple, tra cui iPhone, iPad e Mac. il prezzo \u00e8 fissato a\u00a0<strong>3500 dollari<\/strong>.<\/p>\n\n\n\n<p>Oltre al Vision Pro, Apple ha annunciato anche una serie di nuovi Mac, tra cui l&#8217;<strong>M2 Ultra<\/strong>, ancora pi\u00f9 potente del suo predecessore. L&#8217;azienda ha anche presentato un nuovo sistema operativo, visionOS, progettato appositamente per essere utilizzato con l&#8217;headset Vision Pro.<\/p>\n\n\n\n<p>Infine, Apple ha annunciato una serie di aggiornamenti al suo popolare sistema operativo iOS, e cio\u00e8 l&#8217;attesissimo <strong>iOS 17<\/strong>. Il nuovo aggiornamento include una serie di nuove funzionalit\u00e0 e miglioramenti, tra cui un maggiore controllo della privacy, una migliore funzionalit\u00e0 di Siri e un Centro di Controllo ridisegnato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Apple WWDC 2023 (Worldwide Developers Conference) \u00e8 uno degli eventi tecnologici pi\u00f9 attesi dell&#8217;anno e l&#8217;edizione 2023 non ha deluso le aspettative. <\/p>\n","protected":false},"author":1,"featured_media":8341,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[85],"tags":[84,168,86,167,108],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/scontissimo.com\/index.php\/wp-json\/wp\/v2\/posts\/8339"}],"collection":[{"href":"https:\/\/scontissimo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/scontissimo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/scontissimo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/scontissimo.com\/index.php\/wp-json\/wp\/v2\/comments?post=8339"}],"version-history":[{"count":1,"href":"https:\/\/scontissimo.com\/index.php\/wp-json\/wp\/v2\/posts\/8339\/revisions"}],"predecessor-version":[{"id":8342,"href":"https:\/\/scontissimo.com\/index.php\/wp-json\/wp\/v2\/posts\/8339\/revisions\/8342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/scontissimo.com\/index.php\/wp-json\/wp\/v2\/media\/8341"}],"wp:attachment":[{"href":"https:\/\/scontissimo.com\/index.php\/wp-json\/wp\/v2\/media?parent=8339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/scontissimo.com\/index.php\/wp-json\/wp\/v2\/categories?post=8339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/scontissimo.com\/index.php\/wp-json\/wp\/v2\/tags?post=8339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}